{"id":1150,"date":"2022-01-09T18:14:23","date_gmt":"2022-01-09T18:14:23","guid":{"rendered":"https:\/\/xn--sg-pristblich-ifb.de\/?page_id=1150"},"modified":"2022-01-10T19:58:31","modified_gmt":"2022-01-10T19:58:31","slug":"spielberichte","status":"publish","type":"page","link":"https:\/\/xn--sg-pristblich-ifb.de\/home\/spielberichte\/","title":{"rendered":"Spielberichte"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1150\" class=\"elementor elementor-1150\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4f83395 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4f83395\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b5cda97\" data-id=\"b5cda97\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eb671cf elementor-widget elementor-widget-wp-widget-ocean_custom_menu\" data-id=\"eb671cf\" data-element_type=\"widget\" data-widget_type=\"wp-widget-ocean_custom_menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"oceanwp-custom-menu clr ocean_custom_menu-REPLACE_TO_ID left dropdown-hover\"><ul id=\"menu-hauptmenue\" class=\"dropdown-menu sf-menu\"><li  id=\"menu-item-19\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-19\"><a href=\"https:\/\/xn--sg-pristblich-ifb.de\/home\/\" class=\"menu-link\">Startseite<\/a><\/li>\n<li  id=\"menu-item-1515\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1515\"><a href=\"https:\/\/xn--sg-pristblich-ifb.de\/home\/webcam\/\" class=\"menu-link\">Webcam<\/a><\/li>\n<li  id=\"menu-item-1180\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1180\"><a href=\"https:\/\/xn--sg-pristblich-ifb.de\/home\/galerie\/\" class=\"menu-link\">Galerie<\/a><\/li>\n<li  id=\"menu-item-1243\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1243\"><a href=\"https:\/\/xn--sg-pristblich-ifb.de\/home\/menue-sport\/\" class=\"menu-link\">Sport<\/a><\/li>\n<li  id=\"menu-item-644\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-644\"><a href=\"https:\/\/xn--sg-pristblich-ifb.de\/home\/sponsoren\/\" class=\"menu-link\">Sponsoren<\/a><\/li>\n<li  id=\"menu-item-334\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-334\"><a href=\"https:\/\/sg-prist\u00e4blich.de\/wp-login.php\" class=\"menu-link\">Mitgliederbereich<\/a><\/li>\n<\/ul><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d6b78a9 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"d6b78a9\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;shape_divider_bottom&quot;:&quot;split&quot;,&quot;shape_divider_bottom_negative&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 20\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M519.8,0.2c-11,0-19.8,8.5-19.8,19c0-10.4-8.8-19-19.8-19L0,0v20h1000V0.2H519.8z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d2ae5fe\" data-id=\"7d2ae5fe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-128d5d0 elementor-widget elementor-widget-heading\" data-id=\"128d5d0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00dcbersicht Spielberichte<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b168f54 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b168f54\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9a1a0db\" data-id=\"9a1a0db\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00dcbersicht Spielberichte<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ocean_post_layout":"full-screen","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"off","ocean_display_header":"off","ocean_header_style":"top","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"2","ocean_menu_typo_font_family":"Pontano Sans","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"#ff9800","ocean_menu_link_color_hover":"#ff9800","ocean_menu_link_color_active":"#000000","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"rgba(0,0,0,0)","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"#ffffff","ocean_menu_social_hover_links_color":"#ffffff","ocean_disable_title":"on","ocean_disable_heading":"default","ocean_post_title":".","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"#ffffff","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"off","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","footnotes":""},"_links":{"self":[{"href":"https:\/\/xn--sg-pristblich-ifb.de\/home\/wp-json\/wp\/v2\/pages\/1150"}],"collection":[{"href":"https:\/\/xn--sg-pristblich-ifb.de\/home\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/xn--sg-pristblich-ifb.de\/home\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/xn--sg-pristblich-ifb.de\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/xn--sg-pristblich-ifb.de\/home\/wp-json\/wp\/v2\/comments?post=1150"}],"version-history":[{"count":13,"href":"https:\/\/xn--sg-pristblich-ifb.de\/home\/wp-json\/wp\/v2\/pages\/1150\/revisions"}],"predecessor-version":[{"id":1257,"href":"https:\/\/xn--sg-pristblich-ifb.de\/home\/wp-json\/wp\/v2\/pages\/1150\/revisions\/1257"}],"wp:attachment":[{"href":"https:\/\/xn--sg-pristblich-ifb.de\/home\/wp-json\/wp\/v2\/media?parent=1150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}